{"id":19258,"date":"2020-04-08T09:24:00","date_gmt":"2020-04-08T07:24:00","guid":{"rendered":"https:\/\/www.freelance.de\/blog\/?p=19258"},"modified":"2024-02-02T17:00:35","modified_gmt":"2024-02-02T16:00:35","slug":"krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten","status":"publish","type":"post","link":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/","title":{"rendered":"Krisen meistern: 3 Dinge, die Gr\u00fcnder jetzt umsetzen sollten"},"content":{"rendered":"\n<p><strong>Die Wirtschaftskraft schwankt und die Prognosen sind so unsicher wie selten zuvor. In Deutschland scheint gerade niemand wirklich zu wissen, wo es mit der Wirtschaft hingeht. Das stellt Gr\u00fcnder vor die Herausforderung, gleichzeitig Unternehmenswachstum umzusetzen und sich f\u00fcr die Krise zu wappnen.<\/strong><\/p>\n\n\n\n<p>Die Zeichen stehen\nauf st\u00fcrmischer Unsicherheit. Die n\u00e4chste (Welt-) Wirtschaftskrise wird an\njeder Ecke angek\u00fcndigt &#8211; dann wieder nicht &#8211; und dann doch. Eines scheint klar:\nein Boom steht nicht bevor. Doch wie mit einer Rezession oder Krise als Gr\u00fcnder\numgehen? In der Gr\u00fcndungsphase auf eine Krise zu reagieren kann zu einer\nenormen Herausforderung werden und sogar das Ende des Unternehmens bedeuten,\nbevor es richtig durchgestartet ist.<\/p>\n\n\n\n<p>Der Umgang mit\nKonjunkturschwankungen ist besonders f\u00fcr Start ups, Selbst\u00e4ndige und junge\nUnternehmen von Bedeutung, da sie sich nicht auf gro\u00dfe R\u00fccklagen und eine\nbedeutende Marktstellung verlassen k\u00f6nnen, die es ihnen erlaubt, die Krise\n\u201causzusitzen\u201d oder einfach mal keine \u00fcppigen Boni am Jahresende auszubezahlen.\nIm Gegenteil: der aktive Umgang mit der Krise ist gefordert und der Irrglaube,\neiner Krise hilflos ausgeliefert zu sein, muss \u00fcber Bord geworfen werden.\nLangfristig erfolgreiche Unternehmer, die ein Unternehmen aufgebaut haben, das\nf\u00fcr sie arbeitet anstatt andersherum, wissen Krisenzeiten f\u00fcr sich zu nutzen.\nHier 3 Tipps, wie auch Sie sicher durch die Krise kommen und sie f\u00fcr sich zu\nnutzen lernen:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1.Mindset<\/h2>\n\n\n\n<p>Krisen beginnen im\nKopf. Das wichtigste was Sie begreifen m\u00fcssen, um eine Krise zu meistern ist,\ndass sie von Ihrer Einstellung zu ihr abh\u00e4ngt. Das Wort \u2018Krise\u2019 bedeutet\nurspr\u00fcnglich nicht Panik, sondern <em>Entscheidung<\/em>.\nDas hei\u00dft, es liegt an Ihnen, ob diese Entscheidungssituation Ihr Untergang\noder Ihre Chance ist. <\/p>\n\n\n\n<p>Nutzen Sie die\nKrise also, um voranzukommen. W\u00e4hrend der Rest der Welt in Panik verf\u00e4llt,\nerkennen Sie die Chancen, die sie bietet. Die Gelegenheit ist perfekt, um Ihre\ngenaue Situation, Ihren USP und Ihre Mitarbeiter zu analysieren.<\/p>\n\n\n\n<p>Erstellen Sie ein\nBoard mit allen M\u00f6glichkeiten, Stellschrauben und Perspektiven, die sich Ihnen\nbieten. Alles, was unmittelbar zum Erfolg Ihres Unternehmens beitr\u00e4gt, kommt in\ndie Alpha-Kategorie. In die Beta-Kategorie kommt alles, was wichtig ist, aber\nauch ein paar Monate in der Schublade liegen bleiben kann. Die Gamma-Kategorie\nbeinhaltet alles, was Ihnen und Ihrem Team Freude bereitet, Sie langfristig\nnach vorne bringt aber nicht direkt mit Ihrem Produkt oder Ihrer Dienstleistung\nzu tun hat. Diese Klarheit erm\u00f6glicht es Ihnen in einer Krise schnell die\nnotwendigen Entscheidungen zu treffen, strategisch zu planen und Ihre n\u00e4chsten\nSchritte zu priorisieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2.Erschlie\u00dfen Sie neue Vertriebswege<\/h2>\n\n\n\n<p>Sie suchen schon\nlange nach einem Grund neue Vertriebswege zu testen? Hier ist er. In der Krise\ngilt ganz besonders: verkaufen, verkaufen, verkaufen. In der Zeit, wo Ihre\n(potenziellen) Kunden ihr Geld besonders eng beisammen halten, m\u00fcssen Sie mehr\nleisten, um sie von Ihrem Produkt oder Ihrer Dienstleistung zu \u00fcberzeugen.\nInsbesondere dann, wenn Sie ein neuartiges Produkt auf den Markt bringen und\nSie Ihre Existenz und den Mehrwert erst noch kommunizieren m\u00fcssen. Wie k\u00f6nnte\ndas effektiver klappen, als \u00fcber neue Vertriebswege?!<\/p>\n\n\n\n<p>Verlassen Sie\ngewohnte Bahnen und testen Sie neue Kan\u00e4le um zu verkaufen. Wechseln Sie daf\u00fcr\nbeispielsweise von der Plakatwand zum Brief oder von den Google Ads zu\nLinkedIn. Das wichtigste hier: auffallen. Nie ist es wichtiger sich von der\nMasse abzuheben als w\u00e4hrend einer Krise. Stellen Sie heraus, <strong>was Sie gerade jetzt unersetzlich macht<\/strong>\nund Sie Ihre Kunden voran bringen. So kann Ihnen die Krise nichts anhaben.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3.Prozesse stabilisieren und automatisieren<\/h2>\n\n\n\n<p>Die wenigsten\nUnternehmen sind tats\u00e4chlich so aufgebaut, dass sie f\u00fcr den Unternehmer\narbeiten, anstatt andersherum. In einer Krise kann das den Genickbruch f\u00fcr den\nGr\u00fcnder bedeuten.<\/p>\n\n\n\n<p>Warum? Weil\nMitarbeiter in einer Krise kurzfristig kommen und gehen. H\u00e4ngen die einzelnen\nArbeitsschritte dann an einer einzelnen Person, oder noch schlimmer, am\nUnternehmer selbst, geht es nur noch abw\u00e4rts. Die Prozesse m\u00fcssen stabil und\nautomatisiert sein, damit Sie nicht auf den einzelnen Mitarbeiter angewiesen\nsind und gleichzeitig nicht selbst operativ t\u00e4tig werden m\u00fcssen. In einer\nst\u00fcrmischen Zeit ist es das wichtigste, dass der Kapit\u00e4n an Deck die Situation\nunter Kontrolle beh\u00e4lt. Es gibt keinen wichtigeren Zeitpunkt als eine Krise, um\nals Unternehmer den strategischen \u00dcberblick zu behalten.<\/p>\n\n\n\n<p>Dies ist der\nperfekte Zeitpunkt, um die Standardisierung und Automatisierung Ihrer Abl\u00e4ufe\nvorzunehmen. Sch\u00e4rfen Sie Ihren Blick f\u00fcr die wiederkehrenden Arbeitsschritte\nund systematisieren Sie sie. Entwerfen Sie einen multiplizierbaren\nOnboardingprozess, sodass neue Mitarbeiter sofort produktiv sein k\u00f6nnen &#8211; von\nTag eins an. In einer Krise gibt es schlie\u00dflich keine Zeit zu verlieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit<\/h2>\n\n\n\n<p>Wenn Sie diese drei Punkte umsetzen und leben, l\u00e4uft der Umgang mit der Krise einfach von der Hand und Sie werden sehen, dass es nicht nur Ihr Unternehmen nach innen st\u00e4rkt, sondern auch nach au\u00dfen. Andere Unternehmer und Investoren sehen Ihren Erfolg und wissen zu sch\u00e4tzen, dass eine Chance erkannt und genutzt wird, insbesondere dann, wenn sie nicht offensichtlich auf der Hand liegt. Das ist Ihre Chance, die Krise f\u00fcr Sie zu nutzen und Ihr Unternehmen trotz Rezession nach vorne zu bringen. Ergreifen Sie sie! <\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Wirtschaftskraft schwankt und die Prognosen sind so unsicher wie selten zuvor. In Deutschland scheint gerade niemand wirklich zu wissen, wo es mit der&hellip;<\/p>\n","protected":false},"author":39,"featured_media":19362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[851],"tags":[711,105,179,222],"class_list":["post-19258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tipps-freelancer","tag-coronavirus","tag-freelancer","tag-grundung","tag-selbstandigkeit"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Krisen meistern - Dinge, die G\u00fcnder jetzt umsetzen sollten<\/title>\n<meta name=\"description\" content=\"Um als Gr\u00fcnder durch die Krise gut durchzukommen, gibt es wichtige Dinge, die genau jetzt umgesetzt werden sollten. Die wichtigsten Aspekte finden Sie hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krisen meistern - Dinge, die G\u00fcnder jetzt umsetzen sollten\" \/>\n<meta property=\"og:description\" content=\"Um als Gr\u00fcnder durch die Krise gut durchzukommen, gibt es wichtige Dinge, die genau jetzt umgesetzt werden sollten. Die wichtigsten Aspekte finden Sie hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\" \/>\n<meta property=\"og:site_name\" content=\"freelance.de Blog\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Freelance.de\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-08T07:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T16:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"freelance.de Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freelanceDE\" \/>\n<meta name=\"twitter:site\" content=\"@freelanceDE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"freelance.de Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\"},\"author\":{\"name\":\"freelance.de Redaktion\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/10ac6084b3aa712e4d50188709639844\"},\"headline\":\"Krisen meistern: 3 Dinge, die Gr\u00fcnder jetzt umsetzen sollten\",\"datePublished\":\"2020-04-08T07:24:00+00:00\",\"dateModified\":\"2024-02-02T16:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\"},\"wordCount\":867,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg\",\"keywords\":[\"Coronavirus\",\"Freelancer\",\"Gr\u00fcndung\",\"Selbst\u00e4ndigkeit\"],\"articleSection\":[\"Tipps f\u00fcr Freelancer\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\",\"url\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\",\"name\":\"Krisen meistern - Dinge, die G\u00fcnder jetzt umsetzen sollten\",\"isPartOf\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg\",\"datePublished\":\"2020-04-08T07:24:00+00:00\",\"dateModified\":\"2024-02-02T16:00:35+00:00\",\"description\":\"Um als Gr\u00fcnder durch die Krise gut durchzukommen, gibt es wichtige Dinge, die genau jetzt umgesetzt werden sollten. Die wichtigsten Aspekte finden Sie hier.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage\",\"url\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg\",\"contentUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg\",\"width\":800,\"height\":534,\"caption\":\"Krise entpannt angehen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.freelance.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Krisen meistern: 3 Dinge, die Gr\u00fcnder jetzt umsetzen sollten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#website\",\"url\":\"https:\/\/www.freelance.de\/blog\/\",\"name\":\"freelance.de Blog\",\"description\":\"Alles zum Thema Freelancing\",\"publisher\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.freelance.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#organization\",\"name\":\"freelance.de\",\"alternateName\":\"freelance.de\",\"url\":\"https:\/\/www.freelance.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png\",\"contentUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png\",\"width\":1746,\"height\":411,\"caption\":\"freelance.de\"},\"image\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/Freelance.de\",\"https:\/\/x.com\/freelanceDE\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/10ac6084b3aa712e4d50188709639844\",\"name\":\"freelance.de Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/redaktionsteam-fl.png\",\"contentUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/redaktionsteam-fl.png\",\"caption\":\"freelance.de Redaktion\"},\"description\":\"Unser Online-Redaktionsteam besteht aus aktuellen und ehemaligen Mitarbeiterinnen und Mitarbeitern von freelance.de sowie aus externen Expertinnen und Experten. Sie beherrschen nicht nur die Kunst mit Buchstaben und Worten zu jonglieren, sondern gehen stets die Extrameile, um relevante und aktuelle Themen f\u00fcr Freelancer aufzudecken und wertvolle Erfahrungen weiterzugeben.\",\"url\":\"https:\/\/www.freelance.de\/blog\/author\/freelanceteam\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krisen meistern - Dinge, die G\u00fcnder jetzt umsetzen sollten","description":"Um als Gr\u00fcnder durch die Krise gut durchzukommen, gibt es wichtige Dinge, die genau jetzt umgesetzt werden sollten. Die wichtigsten Aspekte finden Sie hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/","og_locale":"de_DE","og_type":"article","og_title":"Krisen meistern - Dinge, die G\u00fcnder jetzt umsetzen sollten","og_description":"Um als Gr\u00fcnder durch die Krise gut durchzukommen, gibt es wichtige Dinge, die genau jetzt umgesetzt werden sollten. Die wichtigsten Aspekte finden Sie hier.","og_url":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/","og_site_name":"freelance.de Blog","article_publisher":"http:\/\/www.facebook.com\/Freelance.de","article_published_time":"2020-04-08T07:24:00+00:00","article_modified_time":"2024-02-02T16:00:35+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg","type":"image\/jpeg"}],"author":"freelance.de Redaktion","twitter_card":"summary_large_image","twitter_creator":"@freelanceDE","twitter_site":"@freelanceDE","twitter_misc":{"Verfasst von":"freelance.de Redaktion","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#article","isPartOf":{"@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/"},"author":{"name":"freelance.de Redaktion","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/10ac6084b3aa712e4d50188709639844"},"headline":"Krisen meistern: 3 Dinge, die Gr\u00fcnder jetzt umsetzen sollten","datePublished":"2020-04-08T07:24:00+00:00","dateModified":"2024-02-02T16:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/"},"wordCount":867,"commentCount":0,"publisher":{"@id":"https:\/\/www.freelance.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg","keywords":["Coronavirus","Freelancer","Gr\u00fcndung","Selbst\u00e4ndigkeit"],"articleSection":["Tipps f\u00fcr Freelancer"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/","url":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/","name":"Krisen meistern - Dinge, die G\u00fcnder jetzt umsetzen sollten","isPartOf":{"@id":"https:\/\/www.freelance.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage"},"image":{"@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg","datePublished":"2020-04-08T07:24:00+00:00","dateModified":"2024-02-02T16:00:35+00:00","description":"Um als Gr\u00fcnder durch die Krise gut durchzukommen, gibt es wichtige Dinge, die genau jetzt umgesetzt werden sollten. Die wichtigsten Aspekte finden Sie hier.","breadcrumb":{"@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#primaryimage","url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg","contentUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2020\/04\/gr\u00fcnder-freelancer-entspannt.jpg","width":800,"height":534,"caption":"Krise entpannt angehen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.freelance.de\/blog\/krisen-meistern-dinge-die-gruender-jetzt-umsetzen-sollten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freelance.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Krisen meistern: 3 Dinge, die Gr\u00fcnder jetzt umsetzen sollten"}]},{"@type":"WebSite","@id":"https:\/\/www.freelance.de\/blog\/#website","url":"https:\/\/www.freelance.de\/blog\/","name":"freelance.de Blog","description":"Alles zum Thema Freelancing","publisher":{"@id":"https:\/\/www.freelance.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freelance.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.freelance.de\/blog\/#organization","name":"freelance.de","alternateName":"freelance.de","url":"https:\/\/www.freelance.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png","contentUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png","width":1746,"height":411,"caption":"freelance.de"},"image":{"@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/Freelance.de","https:\/\/x.com\/freelanceDE"]},{"@type":"Person","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/10ac6084b3aa712e4d50188709639844","name":"freelance.de Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/redaktionsteam-fl.png","contentUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/redaktionsteam-fl.png","caption":"freelance.de Redaktion"},"description":"Unser Online-Redaktionsteam besteht aus aktuellen und ehemaligen Mitarbeiterinnen und Mitarbeitern von freelance.de sowie aus externen Expertinnen und Experten. Sie beherrschen nicht nur die Kunst mit Buchstaben und Worten zu jonglieren, sondern gehen stets die Extrameile, um relevante und aktuelle Themen f\u00fcr Freelancer aufzudecken und wertvolle Erfahrungen weiterzugeben.","url":"https:\/\/www.freelance.de\/blog\/author\/freelanceteam\/"},false]}},"_links":{"self":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts\/19258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/comments?post=19258"}],"version-history":[{"count":2,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts\/19258\/revisions"}],"predecessor-version":[{"id":19347,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts\/19258\/revisions\/19347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/media\/19362"}],"wp:attachment":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/media?parent=19258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/categories?post=19258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/tags?post=19258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}