{"id":9745,"date":"2016-06-30T10:23:20","date_gmt":"2016-06-30T08:23:20","guid":{"rendered":"https:\/\/www.freelance.de\/blog\/?p=9745"},"modified":"2023-09-14T12:59:10","modified_gmt":"2023-09-14T10:59:10","slug":"ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern","status":"publish","type":"post","link":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/","title":{"rendered":"Ortsunabh\u00e4ngiges Arbeiten: Tipps f\u00fcr Freelancer und Erfahrungen von Arbeitgebern"},"content":{"rendered":"<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9581\" src=\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk700.jpg\" alt=\"community talk\" width=\"700\" height=\"355\" srcset=\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk700.jpg 700w, https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk700-300x152.jpg 300w, https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk700-150x76.jpg 150w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>Flexibel, aber in zweiter Reihe?<\/h3>\n<p>Britta war eine wichtige Mitarbeiterin bei einem Online-Finanz-Magazin, als sie sich entschied, f\u00fcr ein Jahr in Elternzeit zu gehen. Als das Unternehmen w\u00e4hrend ihrer Elternzeit von K\u00f6ln nach Berlin ging, war f\u00fcr sie klar, dass sie nicht mit umziehen w\u00fcrde. Und aus der ehemaligen Ressortleiterin wurde eine Freelancerin, die sich mit ihrem Team vor allem per E-Mail und Skype abstimmte.<\/p>\n<p>Immer mehr Freelancer entscheiden sich f\u00fcr die Ortsunabh\u00e4ngigkeit und werden Teil von virtuellen Teams, die nicht nur zwischen K\u00f6ln und Berlin, sondern weltweit an gemeinsamen Projekten basteln. Wenn Teamleiter ins kalte Wasser geworfen werden und ohne Vorbereitung virtuelle Teammitglieder bekommen, k\u00f6nnen Projekte in Schieflage geraten. Unklare Absprachen, schwelende Konflikte, interkulturelle Missverst\u00e4ndnisse drohen.<\/p>\n<p>Britta w\u00fcrde ihre Unabh\u00e4ngigkeit in ihrer jetzigen Familiensituation niemals gegen den alten Job eintauschen und baut sich derzeit einen gr\u00f6\u00dferen Kundenstamm auf. Doch w\u00e4hrend sie fr\u00fcher an vorderster Front stand, wenn es um Entscheidungen und Themenverteilung ging, verpasst sie heute immer wieder wichtige Neuigkeiten aus dem Team und f\u00fchlt sich zu oft zur\u00fcckgesetzt, wenn es um die Vergabe interessanter Themen geht. Ihre ver\u00e4nderte Stellung im Team zu akzeptieren und weiterhin gute Arbeit leisten zu k\u00f6nnen, das kostet Energie.<\/p>\n<h3>Input durch die kreativsten K\u00f6pfe<\/h3>\n<p>V\u00f6llig andere Erfahrungen machte Arne V\u00f6lker, Partner einer Kommunikationsagentur, <a href=\"http:\/\/www.shadowmountains.pub\/blog\/freelancer-bringen-wirklich-guten-input\/\" target=\"_blank\" rel=\"noopener\">die seit 2011 vollst\u00e4ndig virtuell arbeitet<\/a>. Anlass f\u00fcr die Umstellung war die Entscheidung der Partner, selbst auf Weltreise zu gehen. Von anderen bel\u00e4chelt, stellten sie 2010 kurzerhand ihre kompletten Prozesse um: Ab dem Recruiting l\u00e4uft die gesamte Projektarbeit \u00fcber Skypekonferenzen, ein Projektmanagement-Tool und Chats. Weniger Ablenkung als in herk\u00f6mmlichen Agenturen, daf\u00fcr viel Raum f\u00fcr kreative Arbeit, so lautet das Fazit der Agentur. Wenn sie etwas vermissen, dann das \u201eWir-Gef\u00fchl\u201c, das sich in eng zusammenarbeitenden Teams sonst einstellt. Auch hier konnten sie Abhilfe schaffen: J\u00e4hrliche Teamwochenenden.<\/p>\n<h3>Tipps f\u00fcr virtuelle Teams<\/h3>\n<p>Diese drei Punkte sollten Mitglieder von virtuellen Teams beachten:<\/p>\n<h4>1. Das Management<\/h4>\n<p>Kommunikationsexperten raten dazu, die Umstellung der Prozesse und das Projektmanagement bewusst zu gestalten. Folgende Fragen sollten Sie sich beantworten:<\/p>\n<p><strong>Als Teamleiter:<\/strong><\/p>\n<ul>\n<li>Auf welche unserer St\u00e4rken kann ich bauen? Sind wir besonders flexibel, besonders gut im Onboarding neuer Mitglieder, sehr kommunikativ?<\/li>\n<li>Wie kann ich m\u00f6gliche Schw\u00e4chen ausgleichen?<\/li>\n<li>Wie kann ich mein Team schulen und dabei unterst\u00fctzen, sich selbst zu organisieren?<\/li>\n<li>Wie kommunizieren wir? Reicht die Teilnahme an w\u00f6chentlichen Jour Fixes aus? Welche Informationen muss ich t\u00e4glich weiterleiten?<\/li>\n<li>Wie kann ich eventuell entstehende Konflikte fr\u00fchzeitig erkennen und bearbeiten, etwa durch eine andere Verteilung von Kompetenzen?<\/li>\n<\/ul>\n<p><strong>Als Freelancer:<\/strong><\/p>\n<ul>\n<li>Welche Informationen brauche ich wann, um gute Arbeit leisten zu k\u00f6nnen?<\/li>\n<li>Welche Kommunikationskan\u00e4le kann ich n\u00fctzen, wenn ich schnell Antworten brauche?<\/li>\n<li>Wie kann ich Feedback geben, wenn etwas nicht gut l\u00e4uft?<\/li>\n<\/ul>\n<h4>2. Die richtigen Tools und Prozesse<\/h4>\n<p>Damit die Prozesse f\u00fcr alle nachvollziehbar sind und die Qualit\u00e4tssicherung nicht leidet, muss Transparenz bewusst hergestellt werden. Klare Richtlinien erleichtern dem Team die Arbeit, sollten aber immer wieder auf ihre Praktikabilit\u00e4t hin \u00fcberpr\u00fcft werden.<\/p>\n<p><strong>Als Arbeitgeber:<\/strong><\/p>\n<ul>\n<li>Welche Dokumentationen sind sinnvoll? Welche sind \u00fcberfl\u00fcssig?<\/li>\n<li>Wie kann ich klare Richtlinien aufstellen und kontrollieren, dass sie auch umgesetzt werden?<\/li>\n<li>Wie kann ich Datensicherheit gew\u00e4hrleisten?<\/li>\n<\/ul>\n<p><strong>Als Freelancer:<\/strong><\/p>\n<ul>\n<li>Wie kann ich Dokumentationen in meinen Arbeitsfluss einbauen?<\/li>\n<li>Welche Abstriche muss ich in Sachen Flexibilit\u00e4t machen? Welche Zeiten muss ich dem Projekt einr\u00e4umen?<\/li>\n<li>Wie kann ich Datensicherheit gew\u00e4hrleisten?<\/li>\n<\/ul>\n<h4>3. Vertrauen und Kontakte<\/h4>\n<p>Nicht zuletzt ist es die Atmosph\u00e4re, die ein gutes Team ausmacht, sowie das Vetrauensverh\u00e4ltnis zueinander und die F\u00e4higkeit, f\u00fcreinander einzustehen. Hier sind wieder Arbeitgeber und Freelancer gefragt. W\u00e4hrend die Teamleiter den Freelancern M\u00f6glichkeiten zur Beteiligung bereitstellen m\u00fcssen, sollten Freelancer diese immer wieder aktiv einfordern und eigene Ideen einbringen.<\/p>\n<h3>Jetzt sind Sie dran<\/h3>\n<p><strong>Welche Erfahrungen machen Sie in virtuellen Teams?<\/strong><\/p>\n<p>Hand aufs Herz: Geh\u00f6ren Sie zu den etwa 11% aller Videokonferenzteilnehmer, die, <a href=\"http:\/\/karrierebibel.de\/keine-hosen-in-der-videokonferenz\/\" target=\"_blank\" rel=\"noopener\">glaubt man einer Studie<\/a>, es sich w\u00e4hrend der Konferenz gerne etwas bequemer machen und keine Hosen tragen? Sind Sie, wie Britta inzwischen auch, immer mal wieder mit Handy am Ohr am Spielplatz unterwegs oder erledigen Sie die Gartenarbeit mit Headset am Kopf?<\/p>\n<p><strong><em>Wir freuen uns auf Ihre Anekdoten und Meinungen!<\/em><\/strong><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Flexibel, aber in zweiter Reihe? Britta war eine wichtige Mitarbeiterin bei einem Online-Finanz-Magazin, als sie sich entschied, f\u00fcr ein Jahr in Elternzeit zu gehen.&hellip;<\/p>\n","protected":false},"author":17,"featured_media":9523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[851],"tags":[436,310,105,313],"class_list":["post-9745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tipps-freelancer","tag-community-talk","tag-flexible-arbeitsweise","tag-freelancer","tag-mobil-arbeiten"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virtuelle Teams: Tipps &amp; Tricks f\u00fcr Freelancer<\/title>\n<meta name=\"description\" content=\"Virtuelle Teams &amp; Freelancer: Vorteile treffen auf Herausforderungen in der Kommunikation und Teamdynamik.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virtuelle Teams: Tipps &amp; Tricks f\u00fcr Freelancer\" \/>\n<meta property=\"og:description\" content=\"Virtuelle Teams &amp; Freelancer: Vorteile treffen auf Herausforderungen in der Kommunikation und Teamdynamik.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\" \/>\n<meta property=\"og:site_name\" content=\"freelance.de Blog\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Freelance.de\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-30T08:23:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T10:59:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dagmar Heinze\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@freelanceDE\" \/>\n<meta name=\"twitter:site\" content=\"@freelanceDE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dagmar Heinze\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\"},\"author\":{\"name\":\"Dagmar Heinze\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/e7621d5cb73a239d2272d5b36f21ed08\"},\"headline\":\"Ortsunabh\u00e4ngiges Arbeiten: Tipps f\u00fcr Freelancer und Erfahrungen von Arbeitgebern\",\"datePublished\":\"2016-06-30T08:23:20+00:00\",\"dateModified\":\"2023-09-14T10:59:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\"},\"wordCount\":724,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg\",\"keywords\":[\"Community Talk\",\"flexible Arbeitsweise\",\"Freelancer\",\"mobil Arbeiten\"],\"articleSection\":[\"Tipps f\u00fcr Freelancer\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\",\"url\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\",\"name\":\"Virtuelle Teams: Tipps & Tricks f\u00fcr Freelancer\",\"isPartOf\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg\",\"datePublished\":\"2016-06-30T08:23:20+00:00\",\"dateModified\":\"2023-09-14T10:59:10+00:00\",\"description\":\"Virtuelle Teams & Freelancer: Vorteile treffen auf Herausforderungen in der Kommunikation und Teamdynamik.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage\",\"url\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg\",\"contentUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg\",\"width\":1150,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.freelance.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ortsunabh\u00e4ngiges Arbeiten: Tipps f\u00fcr Freelancer und Erfahrungen von Arbeitgebern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#website\",\"url\":\"https:\/\/www.freelance.de\/blog\/\",\"name\":\"freelance.de Blog\",\"description\":\"Alles zum Thema Freelancing\",\"publisher\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.freelance.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#organization\",\"name\":\"freelance.de\",\"alternateName\":\"freelance.de\",\"url\":\"https:\/\/www.freelance.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png\",\"contentUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png\",\"width\":1746,\"height\":411,\"caption\":\"freelance.de\"},\"image\":{\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/Freelance.de\",\"https:\/\/x.com\/freelanceDE\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/e7621d5cb73a239d2272d5b36f21ed08\",\"name\":\"Dagmar Heinze\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/02\/Dagmar_A-120x120.jpg\",\"contentUrl\":\"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/02\/Dagmar_A-120x120.jpg\",\"caption\":\"Dagmar Heinze\"},\"description\":\"Als Online Marketing Managerin k\u00fcmmert sich Dagmar darum, den Bekanntheitsgrad von freelance.de kontinuierlich zu verbessern. Mit ihren Content-Kreationen auf der Plattform und in Newslettern erobert sie die Herzen unserer User. Dagmar hat ein Faible f\u00fcr guten Kaffee, ist begeisterte Hobbyk\u00f6chin und f\u00e4hrt, wie es sich f\u00fcr ein echtes Nordlicht geh\u00f6rt, auch bei Wind und Wetter mit dem Fahrrad.\",\"sameAs\":[\"http:\/\/www.freelance.de\"],\"url\":\"https:\/\/www.freelance.de\/blog\/author\/dagmar\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virtuelle Teams: Tipps & Tricks f\u00fcr Freelancer","description":"Virtuelle Teams & Freelancer: Vorteile treffen auf Herausforderungen in der Kommunikation und Teamdynamik.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/","og_locale":"de_DE","og_type":"article","og_title":"Virtuelle Teams: Tipps & Tricks f\u00fcr Freelancer","og_description":"Virtuelle Teams & Freelancer: Vorteile treffen auf Herausforderungen in der Kommunikation und Teamdynamik.","og_url":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/","og_site_name":"freelance.de Blog","article_publisher":"http:\/\/www.facebook.com\/Freelance.de","article_published_time":"2016-06-30T08:23:20+00:00","article_modified_time":"2023-09-14T10:59:10+00:00","og_image":[{"width":1150,"height":400,"url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg","type":"image\/jpeg"}],"author":"Dagmar Heinze","twitter_card":"summary_large_image","twitter_creator":"@freelanceDE","twitter_site":"@freelanceDE","twitter_misc":{"Verfasst von":"Dagmar Heinze","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#article","isPartOf":{"@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/"},"author":{"name":"Dagmar Heinze","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/e7621d5cb73a239d2272d5b36f21ed08"},"headline":"Ortsunabh\u00e4ngiges Arbeiten: Tipps f\u00fcr Freelancer und Erfahrungen von Arbeitgebern","datePublished":"2016-06-30T08:23:20+00:00","dateModified":"2023-09-14T10:59:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/"},"wordCount":724,"commentCount":0,"publisher":{"@id":"https:\/\/www.freelance.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage"},"thumbnailUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg","keywords":["Community Talk","flexible Arbeitsweise","Freelancer","mobil Arbeiten"],"articleSection":["Tipps f\u00fcr Freelancer"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/","url":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/","name":"Virtuelle Teams: Tipps & Tricks f\u00fcr Freelancer","isPartOf":{"@id":"https:\/\/www.freelance.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage"},"image":{"@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage"},"thumbnailUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg","datePublished":"2016-06-30T08:23:20+00:00","dateModified":"2023-09-14T10:59:10+00:00","description":"Virtuelle Teams & Freelancer: Vorteile treffen auf Herausforderungen in der Kommunikation und Teamdynamik.","breadcrumb":{"@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#primaryimage","url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg","contentUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2016\/04\/community-talk1150.jpg","width":1150,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.freelance.de\/blog\/ortsunabhaengiges-arbeiten-tipps-fuer-freelancer-und-erfahrungen-von-arbeitgebern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.freelance.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Ortsunabh\u00e4ngiges Arbeiten: Tipps f\u00fcr Freelancer und Erfahrungen von Arbeitgebern"}]},{"@type":"WebSite","@id":"https:\/\/www.freelance.de\/blog\/#website","url":"https:\/\/www.freelance.de\/blog\/","name":"freelance.de Blog","description":"Alles zum Thema Freelancing","publisher":{"@id":"https:\/\/www.freelance.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.freelance.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.freelance.de\/blog\/#organization","name":"freelance.de","alternateName":"freelance.de","url":"https:\/\/www.freelance.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png","contentUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/03\/230315_freelance-de_BLOGLOGO.png","width":1746,"height":411,"caption":"freelance.de"},"image":{"@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/Freelance.de","https:\/\/x.com\/freelanceDE"]},{"@type":"Person","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/e7621d5cb73a239d2272d5b36f21ed08","name":"Dagmar Heinze","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.freelance.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/02\/Dagmar_A-120x120.jpg","contentUrl":"https:\/\/www.freelance.de\/blog\/wp-content\/uploads\/2023\/02\/Dagmar_A-120x120.jpg","caption":"Dagmar Heinze"},"description":"Als Online Marketing Managerin k\u00fcmmert sich Dagmar darum, den Bekanntheitsgrad von freelance.de kontinuierlich zu verbessern. Mit ihren Content-Kreationen auf der Plattform und in Newslettern erobert sie die Herzen unserer User. Dagmar hat ein Faible f\u00fcr guten Kaffee, ist begeisterte Hobbyk\u00f6chin und f\u00e4hrt, wie es sich f\u00fcr ein echtes Nordlicht geh\u00f6rt, auch bei Wind und Wetter mit dem Fahrrad.","sameAs":["http:\/\/www.freelance.de"],"url":"https:\/\/www.freelance.de\/blog\/author\/dagmar\/"},false]}},"_links":{"self":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts\/9745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/comments?post=9745"}],"version-history":[{"count":2,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts\/9745\/revisions"}],"predecessor-version":[{"id":30165,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/posts\/9745\/revisions\/30165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/media\/9523"}],"wp:attachment":[{"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/media?parent=9745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/categories?post=9745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.freelance.de\/blog\/wp-json\/wp\/v2\/tags?post=9745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}